{"id":25097,"date":"2024-07-16T03:12:49","date_gmt":"2024-07-16T03:12:49","guid":{"rendered":"https:\/\/fundacionfleishman.org\/?p=25097"},"modified":"2024-07-16T03:13:38","modified_gmt":"2024-07-16T03:13:38","slug":"fundacion-fleishman-realiza-la-3ra-entrega-de-heroes-extraordinarios-a-fernando-astaburuaga-pazzi","status":"publish","type":"post","link":"https:\/\/fundacionfleishman.org\/en\/fundacion-fleishman-realiza-la-3ra-entrega-de-heroes-extraordinarios-a-fernando-astaburuaga-pazzi\/","title":{"rendered":"Fundaci\u00f3n Fleishman realiza la 3ra entrega de \u201cH\u00e9roes Extraordinarios\u201d a Fernando Astaburuaga Pazzi"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Tampico, Tamaulipas.-<\/strong> Fundacion Fleishman hace entrega del tercer premio de la Convocatoria H\u00e9roes Extraordinarios al ganador reconocido como el \u201cH\u00e9roe Extraordinario del A\u00f1o\u201d que obtuvo durante la celebraci\u00f3n del 50 Aniversario de la Fundaci\u00f3n Fleishman realizada el pasado mes de noviembre de 2023.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e9roes Extraordinarios, fue un llamado a la comunidad y las asociaciones para identificar, nominar y reconocer a aquellas personas que en nuestra regi\u00f3n van m\u00e1s all\u00e1 de su deber y entregan esfuerzos extraordinarios para generar cambios de alto impacto en personas, familias y comunidades.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El premio de \u201cH\u00e9roe Extraordinario del A\u00f1o\u201d se entreg\u00f3 a Fernando Astaburuaga Pazzi, fundador y actual director de Alimentos para la Caridad. Su labor se centra en recuperar 300 toneladas mensuales de alimentos que benefician a m\u00e1s de 14,000 personas en insuficiencia alimentaria. Adem\u00e1s, fund\u00f3 la Casa Hogar Villa de la Caridad, A.C., donde ofrece calidad de vida de forma gratuita a 18 adultos mayores que se encontraban en desamparo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Este reconocimiento es el resultado del apoyo de miles de personas que respaldan tanto a m\u00ed persona como a Alimentos para la Caridad, permitiendo as\u00ed la continuidad de nuestra misi\u00f3n. El haber sido reconocido en esta Convocatoria, garantiz\u00f3 que el alimento llegue a las familias m\u00e1s necesitadas del sur de Tamaulipas y Norte de Veracruz.&#8221;, resalt\u00f3 con emoci\u00f3n Fernando Astaburuaga Pazzi, Fundador y Director actual de Alimentos para la Caridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con los recursos obtenidos gracias al reconocimiento de la Fundaci\u00f3n Fleishman, adquirieron un cami\u00f3n de carga marca Kenworth T370 que permitir\u00e1 aumentar la capacidad de acopio y distribuci\u00f3n de alimentos, que ser\u00e1n destinados a beneficiar a miles personas que sufren de insuficiencia alimentaria en el sur de Tamaulipas y el norte de Veracruz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUn h\u00e9roe no requiere ser f\u00edsicamente fuerte para ayudar o vestir un s\u00faper traje que lo distinga. Un h\u00e9roe extraordinario necesita resistencia ante la adversidad, aliados para<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">formar un gran equipo, una mente creativa y un enorme coraz\u00f3n para perseguir objetivos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">que cambien la vida de miles de personas\u201d expres\u00f3 Mariana Priego Zavala, Directora de la Fundaci\u00f3n Fleishman.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a esta iniciativa,&nbsp; Fundaci\u00f3n Fleishman reafirma su compromiso de impulsar y fortalecer a las asociaciones y organizaciones sociales, ratificando que en nuestra regi\u00f3n existen personas excepcionales que d\u00eda a d\u00eda llevan a cabo acciones extraordinarias.&nbsp;&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Tampico, Tamaulipas.- Fundacion Fleishman hace entrega del tercer premio de la Convocatoria H\u00e9roes Extraordinarios al ganador reconocido como el \u201cH\u00e9roe Extraordinario del A\u00f1o\u201d que obtuvo durante la celebraci\u00f3n del 50&hellip;<\/p>","protected":false},"author":1,"featured_media":25098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-missions"],"_links":{"self":[{"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/posts\/25097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/comments?post=25097"}],"version-history":[{"count":0,"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/posts\/25097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/media\/25098"}],"wp:attachment":[{"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/media?parent=25097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/categories?post=25097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionfleishman.org\/en\/wp-json\/wp\/v2\/tags?post=25097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}